{"id":285316,"date":"2023-04-20T17:24:44","date_gmt":"2023-04-20T15:24:44","guid":{"rendered":"https:\/\/casaomnia.it\/?post_type=product&#038;p=285316"},"modified":"2026-04-13T13:15:26","modified_gmt":"2026-04-13T11:15:26","slug":"aufsatzwaschbecken-stone-tree-cipi","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/","title":{"rendered":"Aufsatzwaschbecken Stone Tree Cip\u00ec"},"content":{"rendered":"<h2 style=\"text-align: center;\">Aufsatzwaschbecken Stone Tree Cip\u00ec<\/h2>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-284966\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg\" alt=\"cip\u00ec Stein Baum Holz Arbeitsplatte Waschbecken\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi-100x100.jpg 100w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Stone Tree ist ein Waschtisch von Cip\u00ec, der aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und erz\u00e4hlt uns von Jahrtausenden, es zeigt uns versteinerte Adern und Rinde, es gibt unwiederholbare Formen ab! Das fotografierte Exemplar ist ein nicht wiederholbares Beispiel in Serie.<\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-284962\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi.jpg\" alt=\"Waschtischplatte Waschbecken Holz Stein Detail cip\u00ec\" width=\"742\" height=\"742\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi.jpg 742w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi-100x100.jpg 100w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-dettaglio-stone-tree-cipi-150x150.jpg 150w\" sizes=\"auto, (max-width: 742px) 100vw, 742px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Vorl\u00e4ufige Messungen:<\/h3>\n<ul>\n<li>40\u00f8 &#8211; h15 &#8211; Loch 4,5 cm<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2023\/01\/logo-cipi-casaomnia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-284733\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2023\/01\/logo-cipi-casaomnia.jpg\" alt=\"logo-cipi-casaomnia\" width=\"400\" height=\"200\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2023\/01\/logo-cipi-casaomnia.jpg 400w, https:\/\/casaomnia.it\/wp-content\/uploads\/2023\/01\/logo-cipi-casaomnia-300x150.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Produkte, Design, Forschung und Emotionen aus der Welt des Badezimmers ( &#8230;. und nicht nur ) Cip\u00ec srl wurde 2003 gegr\u00fcndet und produziert, entwirft und vertreibt seitdem M\u00f6bel und Accessoires f\u00fcr das Badezimmer und den Wohnbereich. Der Hauptzielmarkt ist nach wie vor die Einrichtung von Badezimmern. Arbeitsplatten, Waschbecken, M\u00f6bel und Spiegel sind die repr\u00e4sentativsten Produktkategorien in ihrem Katalog. Holz, Stein, Harz und Metall sind die Materialien, aus denen die Produkte hergestellt werden, die den Stil von Cip\u00ec am besten repr\u00e4sentieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.<\/p>\n","protected":false},"featured_media":284969,"template":"","meta":[],"product_brand":[33120],"product_cat":[289,28284],"product_tag":[43166],"class_list":["post-285316","product","type-product","status-publish","has-post-thumbnail","product_brand-cipi-de","product_cat-aufsatzwaschbecken","product_cat-steinwaschbecken","product_tag-stone-tree-de","wcpa_has_options","first","onbackorder","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aufsatzwaschbecken Stone Tree Cip\u00ec - CasaOmnia<\/title>\n<meta name=\"description\" content=\"Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aufsatzwaschbecken Stone Tree Cip\u00ec - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T11:15:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;718,00 Inkl. MwSt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"bei Nachbestellung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/\",\"name\":\"Aufsatzwaschbecken Stone Tree Cip\u00ec - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg\",\"datePublished\":\"2023-04-20T15:24:44+00:00\",\"dateModified\":\"2026-04-13T11:15:26+00:00\",\"description\":\"Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"cip\u00ec Stein Baum Holz Arbeitsplatte Waschbecken\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/aufsatzwaschbecken-stone-tree-cipi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Badezimmer\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/produkt-kategorie\\\/badezimmer\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Waschbecken\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/produkt-kategorie\\\/badezimmer\\\/waschbecken\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Aufsatzwaschbecken\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/produkt-kategorie\\\/badezimmer\\\/waschbecken\\\/aufsatzwaschbecken\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Aufsatzwaschbecken Stone Tree Cip\u00ec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Cip\u00ec\" \/>\n<meta property=\"product:price:amount\" content=\"718.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"CP950\/T\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aufsatzwaschbecken Stone Tree Cip\u00ec - CasaOmnia","description":"Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/","og_locale":"de_DE","og_type":"article","og_title":"Aufsatzwaschbecken Stone Tree Cip\u00ec - CasaOmnia","og_description":"Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.","og_url":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-13T11:15:26+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Preis":"&euro;&nbsp;718,00 Inkl. MwSt","Verf\u00fcgbarkeit":"bei Nachbestellung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/","url":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/","name":"Aufsatzwaschbecken Stone Tree Cip\u00ec - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg","datePublished":"2023-04-20T15:24:44+00:00","dateModified":"2026-04-13T11:15:26+00:00","description":"Stone Tree ist ein Aufsatzwaschbecken, das aus einem versteinerten Baumstamm geschnitzt wurde. Holz wird zu Stein und nimmt unwiederholbare Formen an.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/11\/lavabo-da-appoggio-legno-pietra-stone-tree-cipi.jpg","width":1000,"height":1000,"caption":"cip\u00ec Stein Baum Holz Arbeitsplatte Waschbecken"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/de\/shop\/aufsatzwaschbecken-stone-tree-cipi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/de\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Badezimmer","item":"https:\/\/casaomnia.it\/de\/produkt-kategorie\/badezimmer\/"},{"@type":"ListItem","position":4,"name":"Waschbecken","item":"https:\/\/casaomnia.it\/de\/produkt-kategorie\/badezimmer\/waschbecken\/"},{"@type":"ListItem","position":5,"name":"Aufsatzwaschbecken","item":"https:\/\/casaomnia.it\/de\/produkt-kategorie\/badezimmer\/waschbecken\/aufsatzwaschbecken\/"},{"@type":"ListItem","position":6,"name":"Aufsatzwaschbecken Stone Tree Cip\u00ec"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/de\/#website","url":"https:\/\/casaomnia.it\/de\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/de\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casaomnia.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"Cip\u00ec","product_price_amount":"718.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"CP950\/T","product_condition":"new"},"wcpa_form_fields":{"wcpaData":{"product":{"product_price":718,"price_html":"<del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>&nbsp;1.041,00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Urspr\u00fcnglicher Preis war: &euro;&nbsp;1.041,00<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>&nbsp;718,00<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Aktueller Preis ist: &euro;&nbsp;718,00.<\/span> <small class=\"woocommerce-price-suffix\">Inkl. MwSt<\/small>","original_product_price":1041,"price_including_tax":718,"price_excluding_tax":588.52459,"product_id":{"parent":285316,"variation":false},"is_variable":false,"stock_status":"onbackorder","stock_quantity":null,"parent_sku":"CP950\/T","product_attributes":{"pa_colore-copripiletta":{"is_variation":false,"values":["alpine-snow-de","blu-sardinia-de","emerald-buddha-de","mustard-yellow-de","night-shift-de","smoke-grey-de"]}},"custom_fields":[],"is_taxable":true,"product_name":"Aufsatzwaschbecken Stone Tree Cip\u00ec","hasImage":false},"fields":{"sec_8644bdeda66f21":{"extra":{"key":"sec_8644bdeda66f21","section_id":"sec_8644bdeda66f21","name":"Default","status":1,"cl_rule":"show","enableCl":false,"relations":[],"toggle":true,"title_tag":"h3","show_title":false,"showPrice":"default","form_id":462730,"form_rules":{"exclude_from_discount":false,"fee_label":"Fee","disp_hide_options_price":false,"disp_show_section_price":false,"disp_show_field_price":true,"layout_option":"standard","pric_use_as_fee":false,"process_fee_as":"woo_fee"},"layout_option":"standard"},"fields":[[{"type":"image-group","label":"Color Code","elementId":"wcpa-image-group-1653648545334","inline":true,"priceOptions":"different_for_all","pricingType":"fixed","enable_popup":"no","name":"image-group-1653648545334","disp_type":"square","img_selection_type":"outline","other_text":"Other","enableCl":true,"cl_rule":"show","cl_val":"42417","col":6,"values":[{"label":"Nero Lucido - 008","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Nero-Lucido-008.jpg","image_id":"274840","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Nero-Lucido-008.jpg","value":"0","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Nero-Lucido-008.jpg","gt_translate_keys":["label"]},{"label":"Lino Lucido - 069","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Lino-Lucido-069.jpg","image_id":"274836","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Lino-Lucido-069.jpg","value":"1","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Lino-Lucido-069.jpg","gt_translate_keys":["label"]},{"label":"Curry Lucido - 071","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Curry-Lucido-071.jpg","image_id":"274824","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Curry-Lucido-071.jpg","value":"2","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Curry-Lucido-071.jpg","gt_translate_keys":["label"]},{"label":"Fard Lucido - 072","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Fard-Lucido-072.jpg","image_id":"274832","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Fard-Lucido-072.jpg","value":"3","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Fard-Lucido-072.jpg","gt_translate_keys":["label"]},{"label":"T\u00e8 Lucido - 073","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Te-Lucido-073.jpg","image_id":"274848","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Te-Lucido-073.jpg","value":"4","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Te-Lucido-073.jpg","gt_translate_keys":["label"]},{"label":"Corteccia Lucido - 074","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Corteccia-Lucido-074.jpg","image_id":"274820","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Corteccia-Lucido-074.jpg","value":"5","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Corteccia-Lucido-074.jpg","gt_translate_keys":["label"]},{"label":"Ciliegia Lucido - 075","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Ciliegia-Lucido-075.jpg","image_id":"274816","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Ciliegia-Lucido-075.jpg","value":"6","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Ciliegia-Lucido-075.jpg","gt_translate_keys":["label"]},{"label":"Denim Lucido - 076","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Denim-Lucido-076.jpg","image_id":"274828","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Denim-Lucido-076.jpg","value":"7","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Denim-Lucido-076.jpg","gt_translate_keys":["label"]},{"label":"Amazzonia Lucido - 077","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Amazzonia-Lucido-077.jpg","image_id":"274812","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Amazzonia-Lucido-077.jpg","value":"8","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Amazzonia-Lucido-077.jpg","gt_translate_keys":["label"]},{"label":"Rugiada Lucido - 078","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Rugiada-Lucido-078.jpg","image_id":"274844","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Rugiada-Lucido-078.jpg","value":"9","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Rugiada-Lucido-078.jpg","gt_translate_keys":["label"]},{"label":"Antracite Opaco - 013","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Antracite-Opaco-013.jpg","image_id":"274856","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Antracite-Opaco-013.jpg","value":"10","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Antracite-Opaco-013.jpg","gt_translate_keys":["label"]},{"label":"Cemento Opaco - 047","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cemento-Opaco-047.jpg","image_id":"274876","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cemento-Opaco-047.jpg","value":"11","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cemento-Opaco-047.jpg","gt_translate_keys":["label"]},{"label":"Basalto Opaco - 049","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Basalto-Opaco-049.jpg","image_id":"274864","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Basalto-Opaco-049.jpg","value":"12","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Basalto-Opaco-049.jpg","gt_translate_keys":["label"]},{"label":"Sabbia Opaco - 051","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Sabbia-Opaco-051.jpg","image_id":"274908","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Sabbia-Opaco-051.jpg","value":"13","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Sabbia-Opaco-051.jpg","gt_translate_keys":["label"]},{"label":"Argilla Opaco - 052","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Argilla-Opaco-052.jpg","image_id":"274860","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Argilla-Opaco-052.jpg","value":"14","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Argilla-Opaco-052.jpg","gt_translate_keys":["label"]},{"label":"Senape Opaco - 053","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Senape-Opaco-053.jpg","image_id":"274916","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Senape-Opaco-053.jpg","value":"15","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Senape-Opaco-053.jpg","gt_translate_keys":["label"]},{"label":"Vaniglia Opaco - 056","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Vaniglia-Opaco-056.jpg","image_id":"274920","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Vaniglia-Opaco-056.jpg","value":"16","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Vaniglia-Opaco-056.jpg","gt_translate_keys":["label"]},{"label":"Polvere Opaco - 057","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Polvere-Opaco-057.jpg","image_id":"274900","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Polvere-Opaco-057.jpg","value":"17","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Polvere-Opaco-057.jpg","gt_translate_keys":["label"]},{"label":"Prugna Opaco - 058","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Prugna-Opaco-058.jpg","image_id":"274904","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Prugna-Opaco-058.jpg","value":"18","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Prugna-Opaco-058.jpg","gt_translate_keys":["label"]},{"label":"Cenere Opaco - 059","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cenere-Opaco-059.jpg","image_id":"274880","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cenere-Opaco-059.jpg","value":"19","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cenere-Opaco-059.jpg","gt_translate_keys":["label"]},{"label":"Cipria Opaco - 060","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cipria-Opaco-060.jpg","image_id":"274884","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cipria-Opaco-060.jpg","value":"20","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Cipria-Opaco-060.jpg","gt_translate_keys":["label"]},{"label":"Bosco Opaco - 061","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Bosco-Opaco-061.jpg","image_id":"274872","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Bosco-Opaco-061.jpg","value":"21","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Bosco-Opaco-061.jpg","gt_translate_keys":["label"]},{"label":"Gesso Opaco - 062","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Gesso-Opaco-062.jpg","image_id":"274892","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Gesso-Opaco-062.jpg","value":"22","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Gesso-Opaco-062.jpg","gt_translate_keys":["label"]},{"label":"Aloe Opaco - 063","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Aloe-Opaco-063.jpg","image_id":"274852","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Aloe-Opaco-063.jpg","value":"23","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Aloe-Opaco-063.jpg","gt_translate_keys":["label"]},{"label":"Indaco Opaco - 066","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Indaco-Opaco-066.jpg","image_id":"274896","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Indaco-Opaco-066.jpg","value":"24","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Indaco-Opaco-066.jpg","gt_translate_keys":["label"]},{"label":"Salvia Opaco - 067","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Salvia-Opaco-067.jpg","image_id":"274912","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Salvia-Opaco-067.jpg","value":"25","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Salvia-Opaco-067.jpg","gt_translate_keys":["label"]},{"label":"Fango Opaco - 068","price":"","image":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Fango-Opaco-068.jpg","image_id":"274888","thumb":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Fango-Opaco-068.jpg","value":"26","thumb_src":"https:\/\/casaomnia.it\/wp-content\/uploads\/2022\/05\/Fango-Opaco-068.jpg","gt_translate_keys":["label"]}],"relations":[{"operator":false,"rules":[{"operator":false,"rules":{"cl_field":"attribute","cl_relation":"is","cl_val":"nic-farbkarte","cl_field_sub":"pa_finitura-igienico"}}]}],"active":true,"tooltip":"","layOut":"inline","disp_size_img":{"width":"","height":""},"error":false,"gt_translate_keys":["label","tooltip"],"price_dependency":false,"cl_dependency":false,"value":""}]]}},"config":{"price_override":"","enable_recaptcha":false,"bind_quantity":false,"quantity_bind_formula":false,"disp_summ_show_option_price":true,"disp_summ_show_product_price":true,"disp_summ_show_total_price":true,"disp_summ_show_fee":false,"disp_summ_show_discount":false,"summary_title":"","options_total_label":"Options Price","total_label":"Total","options_product_label":"Product Price","fee_label":"Fee","discount_label":"Discount","has_price":true,"has_quantity_formula":false},"mc_unit":1,"tax_rate":1,"tax_rate_real":0.22,"discount":{"percentage":0,"fixed":0},"design":{"conf":{"LabelPosition":"above","DescPosition":"above","UploadField":"custom_1","QuantityFieldStyle":"default"},"css":{"LeftLabelWidth":"120px"}},"formulas":[],"lookuptables":[],"clones":false,"cartKey":false}},"_links":{"self":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product\/285316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/media\/284969"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/media?parent=285316"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_brand?post=285316"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_cat?post=285316"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_tag?post=285316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}