{"id":347886,"date":"2025-01-19T16:00:00","date_gmt":"2025-01-19T15:00:00","guid":{"rendered":"https:\/\/casaomnia.it\/?post_type=product&#038;p=347886"},"modified":"2026-04-13T15:14:17","modified_gmt":"2026-04-13T13:14:17","slug":"freistehende-badewannenmischer-581179-qadra-palazzani","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/","title":{"rendered":"Freistehende Badewannenmischer 581179 Qadra Palazzani"},"content":{"rendered":"<h2 style=\"text-align: center;\">Freistehende Badewannenmischer 581179 Qadra Palazzani<\/h2>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-347876\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\" alt=\"freistehende wannenbatterie qadra palazzani\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani-768x768.jpg 768w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Die freistehende Armatur 581179 Qadra Palazzani ist die perfekte L\u00f6sung f\u00fcr freistehende Badewannen und vereint anspruchsvolles Design und Funktionalit\u00e4t. Mit ihren eleganten, modernen Linien passt sie perfekt in moderne oder klassische Umgebungen und verleiht Ihrem Bad einen Hauch von Stil. <\/p>\n<p>Er ist aus hochwertigen Materialien gefertigt und garantiert Robustheit und Langlebigkeit. Die Struktur des Bodens macht ihn zu einem unverwechselbaren und funktionalen Element, das ideal ist, um eine Atmosph\u00e4re von Luxus und Komfort in Ihrem Badezimmer zu schaffen. Ein Detail, das den Unterschied macht.  <\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-343265\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani.jpeg\" alt=\"995717 palazzani\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani.jpeg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani-370x370.jpeg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani-100x100.jpeg 100w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani-300x300.jpeg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani-150x150.jpeg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/995717-palazzani-768x768.jpeg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Versenkter Korpus f\u00fcr bodenstehende Einhebelmischer.<\/p>\n<h3>Technisches Datenblatt<\/h3>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-347880\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\" alt=\"datenblatt freistehende wannenbatterie qadra palazzani\" width=\"1000\" height=\"1414\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-freestanding-per-vasca-qadra-palazzani.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-freestanding-per-vasca-qadra-palazzani-212x300.jpg 212w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-freestanding-per-vasca-qadra-palazzani-724x1024.jpg 724w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-freestanding-per-vasca-qadra-palazzani-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/10\/logo-palazzani-casaomnia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-339034\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/10\/logo-palazzani-casaomnia.jpg\" alt=\"logo-palazzani-casaomnia\" width=\"100\" height=\"100\"><\/a><\/p>\n<p>Die Familie Palazzani stellt seit \u00fcber 100 Jahren Armaturen her und ist in vier Generationen gewachsen. Heute bietet das Unternehmen neben Armaturen auch Luxusprodukte f\u00fcr Bad, K\u00fcche und Wellness an. Mit einem starken Fokus auf Nachhaltigkeit entwickelt Palazzani Technologien, die Energie sparen und Ressourcen schonen.  <\/p>\n<p>Innovation, hochwertige Materialien und funktionale Sch\u00f6nheit leiten die Vision, die darauf abzielt, Tr\u00e4ume zu erf\u00fcllen und Bed\u00fcrfnisse zu antizipieren. Das Ziel ist es, einen neuen &#8222;Wohnstil&#8220; anzubieten, der jedes Zuhause in einen Raum des t\u00e4glichen Wohlbefindens verwandelt. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf. <\/p>\n","protected":false},"featured_media":347879,"template":"","meta":[],"product_brand":[48565],"product_cat":[361],"product_tag":[49046],"class_list":["post-347886","product","type-product","status-publish","has-post-thumbnail","product_brand-palazzani-de","product_cat-unterputz-brausebatterie","product_tag-qadra-de","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Freistehende Badewannenmischer 581179 Qadra Palazzani - CasaOmnia<\/title>\n<meta name=\"description\" content=\"Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freistehende Badewannenmischer 581179 Qadra Palazzani - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T13:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;946,20 Inkl. MwSt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"bei Nachbestellung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/\",\"name\":\"Freistehende Badewannenmischer 581179 Qadra Palazzani - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\",\"datePublished\":\"2025-01-19T15:00:00+00:00\",\"dateModified\":\"2026-04-13T13:14:17+00:00\",\"description\":\"Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"freistehende wannenbatterie qadra palazzani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/freistehende-badewannenmischer-581179-qadra-palazzani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Badezimmer\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/produkt-kategorie\\\/badezimmer\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Armateuren\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/produkt-kategorie\\\/badezimmer\\\/armateuren\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Unterputz Brausebatterie\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/produkt-kategorie\\\/badezimmer\\\/armateuren\\\/unterputz-brausebatterie\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Freistehende Badewannenmischer 581179 Qadra Palazzani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Palazzani\" \/>\n<meta property=\"product:price:amount\" content=\"946.20\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"581179\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Freistehende Badewannenmischer 581179 Qadra Palazzani - CasaOmnia","description":"Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/","og_locale":"de_DE","og_type":"article","og_title":"Freistehende Badewannenmischer 581179 Qadra Palazzani - CasaOmnia","og_description":"Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf.","og_url":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-13T13:14:17+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Preis":"&euro;&nbsp;946,20 Inkl. MwSt","Verf\u00fcgbarkeit":"bei Nachbestellung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/","url":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/","name":"Freistehende Badewannenmischer 581179 Qadra Palazzani - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg","datePublished":"2025-01-19T15:00:00+00:00","dateModified":"2026-04-13T13:14:17+00:00","description":"Die freistehende Wannenbatterie 581179 Qadra Palazzani vereint Eleganz und Funktionalit\u00e4t. Sie verleiht Stil und Komfort und wertet jede Umgebung auf.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-freestanding-per-vasca-qadra-palazzani.jpg","width":1000,"height":1000,"caption":"freistehende wannenbatterie qadra palazzani"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/de\/shop\/freistehende-badewannenmischer-581179-qadra-palazzani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/de\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Badezimmer","item":"https:\/\/casaomnia.it\/de\/produkt-kategorie\/badezimmer\/"},{"@type":"ListItem","position":4,"name":"Armateuren","item":"https:\/\/casaomnia.it\/de\/produkt-kategorie\/badezimmer\/armateuren\/"},{"@type":"ListItem","position":5,"name":"Unterputz Brausebatterie","item":"https:\/\/casaomnia.it\/de\/produkt-kategorie\/badezimmer\/armateuren\/unterputz-brausebatterie\/"},{"@type":"ListItem","position":6,"name":"Freistehende Badewannenmischer 581179 Qadra Palazzani"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/de\/#website","url":"https:\/\/casaomnia.it\/de\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/de\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casaomnia.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"Palazzani","product_price_amount":"946.20","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"581179","product_condition":"new"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product\/347886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/media\/347879"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/media?parent=347886"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_brand?post=347886"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_cat?post=347886"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_tag?post=347886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}