{"id":33174,"count":28,"description":"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.","link":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/","name":"Lazzarini","slug":"lazzarini-de","taxonomy":"product_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lazzarini Produktliste - CasaOmnia<\/title>\n<meta name=\"description\" content=\"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lazzarini Lista Prodotti - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/brand\\\/lazzarini-de\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/brand\\\/lazzarini-de\\\/\",\"name\":\"Lazzarini Produktliste - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#website\"},\"description\":\"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/brand\\\/lazzarini-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/brand\\\/lazzarini-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lazzarini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lazzarini Produktliste - CasaOmnia","description":"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/","og_locale":"de_DE","og_type":"article","og_title":"Lazzarini Lista Prodotti - CasaOmnia","og_description":"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.","og_url":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/","og_site_name":"CasaOmnia","og_image":[{"width":512,"height":512,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/","url":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/","name":"Lazzarini Produktliste - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/de\/#website"},"description":"Lazzarini Mission ist es, ein Designprodukt zu einem f\u00fcr alle zug\u00e4nglichen Preis anzubieten, ohne auf Qualit\u00e4t verzichten zu m\u00fcssen.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/de\/brand\/lazzarini-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/de\/home-20\/"},{"@type":"ListItem","position":2,"name":"Lazzarini"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/de\/#website","url":"https:\/\/casaomnia.it\/de\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/de\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casaomnia.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]}},"_links":{"self":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_brand\/33174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/casaomnia.it\/de\/wp-json\/wp\/v2\/product?product_brand=33174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}