{"id":358698,"date":"2025-04-11T13:00:00","date_gmt":"2025-04-11T11:00:00","guid":{"rendered":"https:\/\/casaomnia.it\/?post_type=product&#038;p=358698"},"modified":"2026-04-13T15:56:20","modified_gmt":"2026-04-13T13:56:20","slug":"hand-shower-3-jets-9910n6-italo-palazzani","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/","title":{"rendered":"Hand Shower 3 Jets 9910N6 Italo Palazzani"},"content":{"rendered":"<h2 style=\"text-align: center;\">Hand Shower 3 Jets 9910N6 Italo Palazzani<\/h2>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-358694\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg\" alt=\"hand shower 3 jets 9910n6 italo palazzani\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani-768x768.jpg 768w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Hand shower \u00d8110mm 9910N6 Italo Palazzani with 3 adjustable jets, ideal for a personalized shower. Perfect for renewing the bathroom in style and transforming every shower into a moment of pure relaxation. <\/p>\n<h3>Technical sheet<\/h3>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-doccetta-3-getti-9910n6-italo-palazzani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-358690\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-doccetta-3-getti-9910n6-italo-palazzani.jpg\" alt=\"data sheet 3 jets hand shower 9910n6 italo palazzani\" width=\"1000\" height=\"1414\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-doccetta-3-getti-9910n6-italo-palazzani.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-doccetta-3-getti-9910n6-italo-palazzani-212x300.jpg 212w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-doccetta-3-getti-9910n6-italo-palazzani-724x1024.jpg 724w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-doccetta-3-getti-9910n6-italo-palazzani-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/10\/logo-palazzani-casaomnia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-339034\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/10\/logo-palazzani-casaomnia.jpg\" alt=\"logo-palazzani-casaomnia\" width=\"100\" height=\"100\"><\/a><\/p>\n<ul>\n<li>The Palazzani family has been manufacturing faucets for more than 100 years, growing through four generations. In addition to faucets, the company now offers luxury products for the bathroom, kitchen and wellness. With a strong focus on sustainability, Palazzani develops technologies that save energy and protect resources.  <\/li>\n<li>Innovation, quality materials and functional beauty guide its vision, aimed at fulfilling dreams and anticipating needs. The goal is to offer a new &#8220;style of living,&#8221; transforming every home into a space of daily well-being. <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments. <\/p>\n","protected":false},"featured_media":358695,"template":"","meta":[],"product_brand":[48549],"product_cat":[50593],"product_tag":[50578],"class_list":["post-358698","product","type-product","status-publish","has-post-thumbnail","product_brand-palazzani-en","product_cat-hand-showers","product_tag-italo-en","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hand Shower 3 Jets 9910N6 Italo Palazzani - CasaOmnia<\/title>\n<meta name=\"description\" content=\"\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hand Shower 3 Jets 9910N6 Italo Palazzani - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T13:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;16,40 VAT included\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/\",\"name\":\"Hand Shower 3 Jets 9910N6 Italo Palazzani - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/doccetta-3-getti-9910n6-italo-palazzani.jpg\",\"datePublished\":\"2025-04-11T11:00:00+00:00\",\"dateModified\":\"2026-04-13T13:56:20+00:00\",\"description\":\"\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/doccetta-3-getti-9910n6-italo-palazzani.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/doccetta-3-getti-9910n6-italo-palazzani.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"hand shower 3 jets 9910n6 italo palazzani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/hand-shower-3-jets-9910n6-italo-palazzani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bathroom\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/product-category\\\/bathroom\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Taps\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/product-category\\\/bathroom\\\/taps\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Hand Showers\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/product-category\\\/bathroom\\\/taps\\\/hand-showers\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Hand Shower 3 Jets 9910N6 Italo Palazzani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Palazzani\" \/>\n<meta property=\"product:price:amount\" content=\"16.40\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9910N6\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hand Shower 3 Jets 9910N6 Italo Palazzani - CasaOmnia","description":"\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/","og_locale":"en_US","og_type":"article","og_title":"Hand Shower 3 Jets 9910N6 Italo Palazzani - CasaOmnia","og_description":"\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments.","og_url":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-13T13:56:20+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Price":"&euro;&nbsp;16,40 VAT included","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/","url":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/","name":"Hand Shower 3 Jets 9910N6 Italo Palazzani - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg","datePublished":"2025-04-11T11:00:00+00:00","dateModified":"2026-04-13T13:56:20+00:00","description":"\u00d8110mm 9910N6 Italo hand shower with 3 adjustable jets. Ideal for renovating the bathroom in style, it offers personalized showering and relaxing moments.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/doccetta-3-getti-9910n6-italo-palazzani.jpg","width":1000,"height":1000,"caption":"hand shower 3 jets 9910n6 italo palazzani"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/en\/shop\/hand-shower-3-jets-9910n6-italo-palazzani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/en\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bathroom","item":"https:\/\/casaomnia.it\/en\/product-category\/bathroom\/"},{"@type":"ListItem","position":4,"name":"Taps","item":"https:\/\/casaomnia.it\/en\/product-category\/bathroom\/taps\/"},{"@type":"ListItem","position":5,"name":"Hand Showers","item":"https:\/\/casaomnia.it\/en\/product-category\/bathroom\/taps\/hand-showers\/"},{"@type":"ListItem","position":6,"name":"Hand Shower 3 Jets 9910N6 Italo Palazzani"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/en\/#website","url":"https:\/\/casaomnia.it\/en\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/en\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casaomnia.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"Palazzani","product_price_amount":"16.40","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9910N6","product_condition":"new"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product\/358698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/media\/358695"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/media?parent=358698"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product_brand?post=358698"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product_cat?post=358698"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product_tag?post=358698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}