{"id":58156,"date":"2016-01-01T00:00:00","date_gmt":"2015-12-31T23:00:00","guid":{"rendered":"https:\/\/casaomnia.it\/shop\/exposed-mixer-for-bath-with-shower-kit-bellosta-m-due\/"},"modified":"2026-04-10T16:50:13","modified_gmt":"2026-04-10T14:50:13","slug":"external-bathtub-mixer-bellosta-m-due","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/","title":{"rendered":"External Bathtub Mixer Bellosta M-Due"},"content":{"rendered":"<h2 style=\"text-align: center;\">External Bathtub Mixer Bellosta M-Due<\/h2>\n<p style=\"text-align: center;\"><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-364845\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg\" alt=\"external bathtub mixer with fixed hook complete bellosta M-UNO\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1-100x100.jpg 100w, https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>the Bellosta M-due external bathtub mixer consists of traditional cartridge, 150 mm PVC flexible hose. 1\/2&#8243; connections and single-jet cylindrical ABS hand shower.<\/p>\n<p style=\"text-align: justify;\">Care, attention, avant-garde techniques, taste, style and experience are the ingredients of the Bellosta rubinetterie designer collections.<\/p>\n<p>Produced entirely in Italy.<\/p>\n<p><img decoding=\"async\" style=\"width: 100%;\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/logo_bellosta_made_in_italy.jpg\" alt=\"logo_bellosta_made_in_italy\"><\/p>\n<h3>Standard finishes:<\/h3>\n<p style=\"text-align: justify;\">Standard finishes in Chrome, Satin Chrome, Brushed Chrome, Brushed Nickel, Matte White.<\/p>\n<p style=\"text-align: justify;\">For any design requirement, it is possible to request a finish that is not standard in the chosen collection.<\/p>\n<p><img decoding=\"async\" style=\"width: 100%;\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/scheda_colori_bellosta.jpg\" alt=\"tab_colors_bellosta\"><\/p>\n<h3>Technical advice:<\/h3>\n<p style=\"text-align: justify;\">All mixers in the M-Uno\/M-Due collection are tested in their operation at the time of assembly. To ensure the durability of the cartridges over time, it is recommended that the hydraulic system be purged well before installation to remove any debris.<\/p>\n<h3>Technical sheet<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" style=\"width: 100%;\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/scheda_tecnica_miscelatore_esterno_per_vasca_con_gancio_fisso_bellosta_M-DUE_ins.jpg.jpg\" alt=\"technical_sheet_external_mixer_for_bath_with_fixed_hook_bellosta_M-DUE_ins.jpg\"><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white <\/p>\n","protected":false},"featured_media":364846,"template":"","meta":[],"product_brand":[33161],"product_cat":[212],"product_tag":[6058,33511],"class_list":["post-58156","product","type-product","status-publish","has-post-thumbnail","product_brand-bellosta-en","product_cat-bathtub-mixer","product_tag-bellosta-en","product_tag-m-due-en","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>External Bathtub Mixer Bellosta M-Due - CasaOmnia<\/title>\n<meta name=\"description\" content=\"Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"External Bathtub Mixer Bellosta M-Due - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T14:50:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data1\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/\",\"name\":\"External Bathtub Mixer Bellosta M-Due - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg\",\"datePublished\":\"2015-12-31T23:00:00+00:00\",\"dateModified\":\"2026-04-10T14:50:13+00:00\",\"description\":\"Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"external bathtub mixer with fixed hook complete bellosta M-UNO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/external-bathtub-mixer-bellosta-m-due\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bathroom\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/product-category\\\/bathroom\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Taps\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/product-category\\\/bathroom\\\/taps\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Bathtub Mixer\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/product-category\\\/bathroom\\\/taps\\\/bathtub-mixer\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"External Bathtub Mixer Bellosta M-Due\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Bellosta\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"BELLOSTA022\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"External Bathtub Mixer Bellosta M-Due - CasaOmnia","description":"Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/","og_locale":"en_US","og_type":"article","og_title":"External Bathtub Mixer Bellosta M-Due - CasaOmnia","og_description":"Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white","og_url":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-10T14:50:13+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/","url":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/","name":"External Bathtub Mixer Bellosta M-Due - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg","datePublished":"2015-12-31T23:00:00+00:00","dateModified":"2026-04-10T14:50:13+00:00","description":"Bellosta M-Due external bathtub mixer with fixed hook. Available in chrome, satin chrome, brushed chrome, brushed nickel, matte white","breadcrumb":{"@id":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2016\/01\/miscelatore-esterno-per-vasca-con-gancio-fisso-completo-bellosta-M-UNO-1.jpg","width":1000,"height":1000,"caption":"external bathtub mixer with fixed hook complete bellosta M-UNO"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/en\/shop\/external-bathtub-mixer-bellosta-m-due\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/en\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bathroom","item":"https:\/\/casaomnia.it\/en\/product-category\/bathroom\/"},{"@type":"ListItem","position":4,"name":"Taps","item":"https:\/\/casaomnia.it\/en\/product-category\/bathroom\/taps\/"},{"@type":"ListItem","position":5,"name":"Bathtub Mixer","item":"https:\/\/casaomnia.it\/en\/product-category\/bathroom\/taps\/bathtub-mixer\/"},{"@type":"ListItem","position":6,"name":"External Bathtub Mixer Bellosta M-Due"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/en\/#website","url":"https:\/\/casaomnia.it\/en\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/en\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casaomnia.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"Bellosta","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"BELLOSTA022","product_condition":"new"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product\/58156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/media\/364846"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/media?parent=58156"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product_brand?post=58156"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product_cat?post=58156"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/en\/wp-json\/wp\/v2\/product_tag?post=58156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}