{"id":356643,"date":"2025-03-04T13:00:00","date_gmt":"2025-03-04T12:00:00","guid":{"rendered":"https:\/\/casaomnia.it\/?post_type=product&#038;p=356643"},"modified":"2026-04-13T15:38:12","modified_gmt":"2026-04-13T13:38:12","slug":"colonne-de-douche-thermostatique-962281-mimo-palazzani","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/","title":{"rendered":"Colonne De Douche Thermostatique 962281 Mimo Palazzani"},"content":{"rendered":"<h2 style=\"text-align: center;\">Colonne De Douche Thermostatique 962281 Mimo Palazzani<\/h2>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-356633\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\" alt=\"mitigeur thermostatique de douche 962281 mimo palazzani\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani-768x768.jpg 768w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>La colonne de douche thermostatique 962281 Mimo de Palazzani est la solution id\u00e9ale pour une douche confortable et moderne. \u00c9quip\u00e9e d&rsquo;une colonne de douche, d&rsquo;un inverseur, d&rsquo;un flexible de 1,5 m, d&rsquo;une douchette \u00e0 main et d&rsquo;un pommeau de douche, elle offre une exp\u00e9rience compl\u00e8te et personnalisable. Parfaite pour ceux qui veulent allier praticit\u00e9 et style, en transformant chaque douche en un moment de pure d\u00e9tente et de bien-\u00eatre.  <\/p>\n<h3>Fiche Technique<\/h3>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-356637\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\" alt=\"fiche technique mitigeur de douche thermostatique 962281 mimo palazzani\" width=\"1000\" height=\"1414\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-termostatico-doccia-962281-mimo-palazzani-212x300.jpg 212w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-termostatico-doccia-962281-mimo-palazzani-724x1024.jpg 724w, https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/scheda-tecnica-miscelatore-termostatico-doccia-962281-mimo-palazzani-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/10\/logo-palazzani-casaomnia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-339034\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/10\/logo-palazzani-casaomnia.jpg\" alt=\"logo-palazzani-casaomnia\" width=\"100\" height=\"100\"><\/a><\/p>\n<p>La famille Palazzani fabrique des robinets et des accessoires depuis plus de 100 ans, et ce depuis quatre g\u00e9n\u00e9rations. Outre les robinets, l&rsquo;entreprise propose d\u00e9sormais des produits de luxe pour les salles de bains, les cuisines et le bien-\u00eatre. Soucieuse du d\u00e9veloppement durable, Palazzani met au point des technologies qui permettent d&rsquo;\u00e9conomiser l&rsquo;\u00e9nergie et de prot\u00e9ger les ressources.  <\/p>\n<p>L&rsquo;innovation, la qualit\u00e9 des mat\u00e9riaux et la beaut\u00e9 fonctionnelle guident sa vision, qui vise \u00e0 satisfaire les r\u00eaves et \u00e0 anticiper les besoins. L&rsquo;objectif est d&rsquo;offrir un nouveau \u00ab\u00a0style de vie\u00a0\u00bb, en transformant chaque maison en un espace de bien-\u00eatre quotidien. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.<\/p>\n","protected":false},"featured_media":356635,"template":"","meta":[],"product_brand":[48557],"product_cat":[302],"product_tag":[48777],"class_list":["post-356643","product","type-product","status-publish","has-post-thumbnail","product_brand-palazzani-fr","product_cat-melangeurs-de-douche","product_tag-mimo-fr","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Colonne De Douche Thermostatique 962281 Mimo Palazzani - CasaOmnia<\/title>\n<meta name=\"description\" content=\"La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colonne De Douche Thermostatique 962281 Mimo Palazzani - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T13:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;351,30 TVA incluse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En r\u00e9assort\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/\",\"name\":\"Colonne De Douche Thermostatique 962281 Mimo Palazzani - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\",\"datePublished\":\"2025-03-04T12:00:00+00:00\",\"dateModified\":\"2026-04-13T13:38:12+00:00\",\"description\":\"La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"mitigeur thermostatique de douche 962281 mimo palazzani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/colonne-de-douche-thermostatique-962281-mimo-palazzani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salle de Bain\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/salle-de-bain\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Robinets\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/salle-de-bain\\\/robinets\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"M\u00e9langeurs de Douche\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/salle-de-bain\\\/robinets\\\/melangeurs-de-douche\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Colonne De Douche Thermostatique 962281 Mimo Palazzani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Palazzani\" \/>\n<meta property=\"product:price:amount\" content=\"351.30\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"962281\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Colonne De Douche Thermostatique 962281 Mimo Palazzani - CasaOmnia","description":"La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/","og_locale":"fr_FR","og_type":"article","og_title":"Colonne De Douche Thermostatique 962281 Mimo Palazzani - CasaOmnia","og_description":"La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.","og_url":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-13T13:38:12+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Prix":"&euro;&nbsp;351,30 TVA incluse","Disponibilit\u00e9":"En r\u00e9assort"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/","url":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/","name":"Colonne De Douche Thermostatique 962281 Mimo Palazzani - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg","datePublished":"2025-03-04T12:00:00+00:00","dateModified":"2026-04-13T13:38:12+00:00","description":"La colonne de douche thermostatique 962281Palazzani, avec colonne, inverseur, flexible, douchette \u00e0 main et douche de t\u00eate, allie confort et style pour une douche parfaite.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2024\/01\/miscelatore-termostatico-doccia-962281-mimo-palazzani.jpg","width":1000,"height":1000,"caption":"mitigeur thermostatique de douche 962281 mimo palazzani"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/fr\/shop\/colonne-de-douche-thermostatique-962281-mimo-palazzani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/fr\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Salle de Bain","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/salle-de-bain\/"},{"@type":"ListItem","position":4,"name":"Robinets","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/salle-de-bain\/robinets\/"},{"@type":"ListItem","position":5,"name":"M\u00e9langeurs de Douche","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/salle-de-bain\/robinets\/melangeurs-de-douche\/"},{"@type":"ListItem","position":6,"name":"Colonne De Douche Thermostatique 962281 Mimo Palazzani"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/fr\/#website","url":"https:\/\/casaomnia.it\/fr\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/fr\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaomnia.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"Palazzani","product_price_amount":"351.30","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"962281","product_condition":"new"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product\/356643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/media\/356635"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/media?parent=356643"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_brand?post=356643"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_cat?post=356643"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_tag?post=356643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}