{"id":49518,"date":"2016-01-01T00:00:00","date_gmt":"2015-12-31T23:00:00","guid":{"rendered":"https:\/\/casaomnia.it\/shop\/lampe-encastree-4174-basic-collection-9010\/"},"modified":"2026-04-10T16:19:13","modified_gmt":"2026-04-10T14:19:13","slug":"lampe-encastre-4174-basic-collection-9010","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/","title":{"rendered":"Lampe Encastr\u00e9 4174 Basic Collection 9010"},"content":{"rendered":"<h2 style=\"text-align: center;\">Lampe Encastr\u00e9 4174 Basic Collection 9010<\/h2>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-286278\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg\" alt=\"faretto-incasso-9010-novantadieci-4174\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174-100x100.jpg 100w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<h3>BASIC COLLECTION 9010<\/h3>\n<p>Spot encastr\u00e9 4174 Collection de base 9010, polyvalent et fonctionnel, pour une vari\u00e9t\u00e9 de solutions d&rsquo;\u00e9clairage.<\/p>\n<p>&nbsp;<\/p>\n<h3>Fiche Technique<\/h3>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-213159 size-full\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010.jpg\" alt=\"fiche technique lampe encastr\u00e9e 4174 9010\" width=\"1156\" height=\"870\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010.jpg 1156w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010-1000x753.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010-300x226.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010-1024x771.jpg 1024w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/scheda-tecnica-faretto-da-incasso-4174-9010-768x578.jpg 768w\" sizes=\"auto, (max-width: 1156px) 100vw, 1156px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>HOUSING BOX (POUR UNE INSTALLATION SANS PLAFOND OU MUR):<\/h3>\n<p>Le syst\u00e8me des housing box permet le montage des spots encastr\u00e9s \u00e9galement dans les murs de briques.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/faretto_incasso_per_controsoffitto_in_gesso_4174_basic_collection_9010_CONTROCASSA.jpg\" alt=\"faretto_incasso_per_controsoffitto_in_gesso_4174_basic_collection_9010_CONTROCASSA\"><\/p>\n<p>&nbsp;<\/p>\n<h3>Mat\u00e9riau :<\/h3>\n<ul>\n<li>Cristaux de s\u00e9l\u00e9nite pour l&rsquo;\u00e9clairage<\/li>\n<li>Plus de luminosit\u00e9 et de brillance pour les syst\u00e8mes d&rsquo;\u00e9clairage encastr\u00e9s.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/faretto_incasso_per_controsoffitto_in_gesso_4174_basic_collection_9010_cristaly_materiale.jpg\" alt=\"faretto_incasso_per_controsoffitto_in_gesso_4174_basic_collection_9010_cristaly_materiale\"><\/p>\n<h4>CRISTALY 9010:<\/h4>\n<p>D\u00e9j\u00e0 avec AlphaPlus, les produits 9010novantadieci ont \u00e9t\u00e9 distingu\u00e9s d\u00e8s le d\u00e9part par la lunicity du mat\u00e9riel utilis\u00e9. La recherche sans rel\u00e2che dans le choix de nouvelles formulations et dans la cr\u00e9ation de compos\u00e9s avec des caract\u00e9ristiques de plus en plus distinctives et performantes, a permis d\u2019am\u00e9liorer et d\u2019augmenter les caract\u00e9ristiques d\u2019AlphaPlus, de cr\u00e9er un nouveau mat\u00e9riau, une exclusivit\u00e9 Pour les produits 9010novantadieci: CRISTALY.<\/p>\n<p>CRISTALY: des cristaux de s\u00e9l\u00e9nite, un tout-fabriqu\u00e9 en Italie Revolution en 9010 produits. L\u2019appel \u00e0 la s\u00e9l\u00e9nite n\u2019est pas accidentel. La s\u00e9l\u00e9nite se trouve dans la nature sous la forme d\u2019\u00e9cailles transparentes et translucides qui sont parcourues par la lumi\u00e8re.<\/p>\n<p>Cette caract\u00e9ristique a \u00e9t\u00e9 exploit\u00e9e par les Grecs antiques qui l\u2019utilisaient pour la fabrication de dalles transparentes qui ont remplac\u00e9 le verre (encore inconnu), la lumi\u00e8re qui passait \u00e9tait semblable \u00e0 celle de la lune (?????? Selene en grec ou m\u00eame Pierre de lune) . Les Romains l\u2019utilisaient aussi avec les m\u00eames fonctions appel\u00e9es lapis sp\u00e9cularis. En fait, il existe de nombreuses mines et carri\u00e8res de l\u2019\u00e9poque romaine dans le territoire de l\u2019\u00c9milie-Romagne et en Espagne.<\/p>\n<p>Dans le Feng Shui est utilis\u00e9 pendant des si\u00e8cles comme une pierre de clairvoyance pour mettre \u00e0 la vision ou apporter en relief des situations obscures et pour ceux qui veulent clarifier leurs \u00e9motions. Dans Crystallotherapy construit le pont \u00e0 travers lequel les plus hautes fr\u00e9quences de la lumi\u00e8re peuvent \u00eatre int\u00e9gr\u00e9s dans la mati\u00e8re pour vous permettre d\u2019atteindre l\u2019exp\u00e9rience spirituelle. Dissout les vieilles habitudes mentales pour faire place \u00e0 de nouvelles conceptions.<\/p>\n<p>A partir de ce mat\u00e9riau riche en histoire et en suggestions, nos techniciens avec l\u2019aide des technologies les plus modernes, ont cr\u00e9\u00e9 CRISTALY, un compos\u00e9 qui exalte encore plus la lumi\u00e8re, am\u00e9liore la r\u00e9sistance aux chocs thermiques et est compl\u00e8tement compatible avec le Stuccos et mat\u00e9riaux utilis\u00e9s pour les installations de cloison s\u00e8che.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/cristaly_9010_materiali_faretti_incasso.jpg\" alt=\"cristaly_9010_materiali_faretti_incasso\"><\/p>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/04\/logo-9010-novantadieci-casaomnia-2020.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-213168 size-full aligncenter\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/04\/logo-9010-novantadieci-casaomnia-2020.jpg\" alt=\"logo-9010-novantadieci-casaomnia-2020\" width=\"992\" height=\"407\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/04\/logo-9010-novantadieci-casaomnia-2020.jpg 992w, https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/04\/logo-9010-novantadieci-casaomnia-2020-600x246.jpg 600w, https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/04\/logo-9010-novantadieci-casaomnia-2020-300x123.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/04\/logo-9010-novantadieci-casaomnia-2020-768x315.jpg 768w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/a><\/p>\n<h3>SOCI\u00c9T\u00c9 9010 NOVANTADIECI<\/h3>\n<p>Belfiore est n\u00e9 en1968 \u00e0 Nove, au coeur de la V\u00e9n\u00e9tie.<br \/>\nLes d\u00e9buts se situent dans la production de c\u00e9ramiques artisanales, dans une r\u00e9gion riche en mati\u00e8res premi\u00e8res et dans une tradition de fabrication.<br \/>\nDans les ann\u00e9es 80, il entre dans le monde de l&rsquo;\u00e9clairage avec les premi\u00e8res appliques murales en c\u00e9ramique.<br \/>\nEn 2011, 9010 est n\u00e9, qui est imm\u00e9diatement entr\u00e9 sur le march\u00e9 de l&rsquo;\u00e9clairage encastr\u00e9, s&rsquo;imposant pour sa philosophie innovante, l&rsquo;exhaustivit\u00e9 de sa gamme et ses solutions contemporaines, soutenues par de nombreux brevets.<\/p>\n<p>Gr\u00e2ce \u00e0 sa longue exp\u00e9rience dans le secteur de l&rsquo;\u00e9clairage, l&rsquo;entreprise d\u00e9veloppe des cr\u00e9ations originales et \u00e9l\u00e9gantes au design raffin\u00e9 et moderne.<br \/>\nIls parviennent \u00e0 combiner tradition, modernit\u00e9, cr\u00e9ativit\u00e9, utilit\u00e9, s\u00e9curit\u00e9 et design pour \u00e9clairer les espaces avec une large perspective artistique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.<\/p>\n","protected":false},"featured_media":286280,"template":"","meta":[],"product_brand":[33130],"product_cat":[354,351],"product_tag":[6057,33361],"class_list":["post-49518","product","type-product","status-publish","has-post-thumbnail","product_brand-9010-novantadieci-fr","product_cat-au-plafond","product_cat-mur","product_tag-9010-novantadieci-fr","product_tag-basic-fr","first","onbackorder","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lampe Encastr\u00e9 4174 Basic Collection 9010 - CasaOmnia<\/title>\n<meta name=\"description\" content=\"Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampe Encastr\u00e9 4174 Basic Collection 9010 - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T14:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;50,00 TVA incluse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En r\u00e9assort\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/\",\"name\":\"Lampe Encastr\u00e9 4174 Basic Collection 9010 - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/1970\\\/01\\\/faretto-incasso-9010-novantadieci-4174.jpg\",\"datePublished\":\"2015-12-31T23:00:00+00:00\",\"dateModified\":\"2026-04-10T14:19:13+00:00\",\"description\":\"Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/1970\\\/01\\\/faretto-incasso-9010-novantadieci-4174.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/1970\\\/01\\\/faretto-incasso-9010-novantadieci-4174.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"faretto-incasso-9010-novantadieci-4174\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/lampe-encastre-4174-basic-collection-9010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eclairage\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/eclairage\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lampe Encastree\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/eclairage\\\/lampe-encastree\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Au Plafond\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/eclairage\\\/lampe-encastree\\\/au-plafond\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Lampe Encastr\u00e9 4174 Basic Collection 9010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"9010 Novantadieci\" \/>\n<meta property=\"product:price:amount\" content=\"50.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"4174-35\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lampe Encastr\u00e9 4174 Basic Collection 9010 - CasaOmnia","description":"Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/","og_locale":"fr_FR","og_type":"article","og_title":"Lampe Encastr\u00e9 4174 Basic Collection 9010 - CasaOmnia","og_description":"Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.","og_url":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-10T14:19:13+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Prix":"&euro;&nbsp;50,00 TVA incluse","Disponibilit\u00e9":"En r\u00e9assort"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/","url":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/","name":"Lampe Encastr\u00e9 4174 Basic Collection 9010 - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg","datePublished":"2015-12-31T23:00:00+00:00","dateModified":"2026-04-10T14:19:13+00:00","description":"Lampe encastr\u00e9e in cristaly 4174, polyvalent et fonctionnel, pour plafond ou mur, basic collection 9010 Belfiore.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/faretto-incasso-9010-novantadieci-4174.jpg","width":1000,"height":1000,"caption":"faretto-incasso-9010-novantadieci-4174"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/fr\/shop\/lampe-encastre-4174-basic-collection-9010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/fr\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Eclairage","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/eclairage\/"},{"@type":"ListItem","position":4,"name":"Lampe Encastree","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/eclairage\/lampe-encastree\/"},{"@type":"ListItem","position":5,"name":"Au Plafond","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/eclairage\/lampe-encastree\/au-plafond\/"},{"@type":"ListItem","position":6,"name":"Lampe Encastr\u00e9 4174 Basic Collection 9010"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/fr\/#website","url":"https:\/\/casaomnia.it\/fr\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/fr\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaomnia.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"9010 Novantadieci","product_price_amount":"50.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"4174-35","product_condition":"new"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product\/49518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/media\/286280"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/media?parent=49518"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_brand?post=49518"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_cat?post=49518"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_tag?post=49518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}