{"id":49850,"date":"2016-01-01T00:00:00","date_gmt":"2015-12-31T23:00:00","guid":{"rendered":"https:\/\/casaomnia.it\/shop\/mitigeur-bidet-avec-vidage-bellosta-zehn\/"},"modified":"2026-04-10T16:31:19","modified_gmt":"2026-04-10T14:31:19","slug":"mitigeur-de-bidet-avec-vidage-bellosta-zehn","status":"publish","type":"product","link":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/","title":{"rendered":"Mitigeur De Bidet Avec Vidage Bellosta Zehn"},"content":{"rendered":"<h2 style=\"text-align: center;\">Mitigeur De Bidet Avec Vidage Bellosta Zehn<\/h2>\n<p><a href=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-346819\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg\" alt=\"bellosta zhen bidet mixer with pop-up waste\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg 1000w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2-300x300.jpg 300w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2-150x150.jpg 150w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2-768x768.jpg 768w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2-370x370.jpg 370w, https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Le mitigeur de bidet Bellosta de la collection Zehn allie une esth\u00e9tique moderne \u00e0 une fonctionnalit\u00e9 avanc\u00e9e, ce qui le rend parfait pour rehausser l&rsquo;\u00e9l\u00e9gance et la praticit\u00e9 de toute salle de bains. Con\u00e7u avec un entraxe de 95 mm, il s&rsquo;adapte \u00e0 diff\u00e9rentes configurations et offre une solution polyvalente. <\/p>\n<p style=\"text-align: justify;\">Les flexibles d&rsquo;alimentation inclus simplifient l&rsquo;installation, tandis que le syst\u00e8me de chasse d&rsquo;eau int\u00e9gr\u00e9 assure commodit\u00e9 et praticit\u00e9 au quotidien. Les lignes \u00e9pur\u00e9es et la finition chrom\u00e9e durable ajoutent une touche de brillance, transformant votre salle de bains en un espace accueillant et sophistiqu\u00e9. <\/p>\n<h3>Finitions standard<\/h3>\n<ul>\n<li>Chrome<\/li>\n<li>Chrome bross\u00e9<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Pour toute exigence de conception, il est possible de demander une finition qui n&rsquo;est pas standard dans la collection choisie.<\/p>\n<p><img decoding=\"async\" style=\"width: 100%;\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/scheda_colori_bellosta.jpg\" alt=\"tab_colors_bellosta\"><\/p>\n<h3>Conseils techniques<\/h3>\n<p>Tous les m\u00e9langeurs de la collection Zehn sont test\u00e9s au moment de l&rsquo;assemblage. Pour garantir la durabilit\u00e9 des cartouches dans le temps, il est recommand\u00e9 de purger le syst\u00e8me hydraulique bien avant l&rsquo;assemblage afin d&rsquo;\u00e9liminer tout d\u00e9bris. <\/p>\n<h3>Fiche Technique<\/h3>\n<p style=\"text-align: center;\"><img decoding=\"async\" style=\"width: 100%;\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/scheda_tecnica_miscelatore_per_bidet_con_salterello_bellosta_zhen.jpg\" alt=\"fiche technique_m\u00e9langeur_pour_bidet_avec_substrat_bellosta_zhen\"><\/p>\n<p><img decoding=\"async\" style=\"width: 100%;\" src=\"https:\/\/casaomnia.it\/wp-content\/uploads\/2019\/05\/logo_bellosta_made_in_italy.jpg\" alt=\"logo_bellosta_made_in_italy\"><\/p>\n<p>Bellosta Rubinetterie est synonyme d&rsquo;excellence italienne dans la conception et la production de robinetterie de haute qualit\u00e9. Depuis 1961, l&rsquo;entreprise allie savoir-faire artisanal et innovation technologique pour cr\u00e9er des produits qui allient fonctionnalit\u00e9 et esth\u00e9tique.  Chaque robinet est un exemple d&rsquo;attention port\u00e9e aux d\u00e9tails, con\u00e7u pour offrir des solutions \u00e9l\u00e9gantes et durables pour la salle de bains et la cuisine. Bellosta se distingue par son engagement en faveur de la durabilit\u00e9, en utilisant des mat\u00e9riaux \u00e9cologiques et des processus de production respectueux de l&rsquo;environnement. Choisir Bellosta, c&rsquo;est faire entrer le meilleur du Made in Italy dans votre maison, avec un style incomparable et une qualit\u00e9 sans compromis. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.<\/p>\n","protected":false},"featured_media":346821,"template":"","meta":[],"product_brand":[33160],"product_cat":[301],"product_tag":[33667],"class_list":["post-49850","product","type-product","status-publish","has-post-thumbnail","product_brand-bellosta-fr","product_cat-melangeurs-bidet","product_tag-zehn-fr","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mitigeur De Bidet Avec Vidage Bellosta Zehn - CasaOmnia<\/title>\n<meta name=\"description\" content=\"Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitigeur De Bidet Avec Vidage Bellosta Zehn - CasaOmnia\" \/>\n<meta property=\"og:description\" content=\"Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/\" \/>\n<meta property=\"og:site_name\" content=\"CasaOmnia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CasaOmnia.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T14:31:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CasaOmnia_Shop\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En r\u00e9assort\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/\",\"name\":\"Mitigeur De Bidet Avec Vidage Bellosta Zehn - CasaOmnia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/1970\\\/01\\\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg\",\"datePublished\":\"2015-12-31T23:00:00+00:00\",\"dateModified\":\"2026-04-10T14:31:19+00:00\",\"description\":\"Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/1970\\\/01\\\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/1970\\\/01\\\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"bellosta zhen bidet mixer with pop-up waste\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/home-20\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salle de Bain\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/salle-de-bain\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Robinets\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/salle-de-bain\\\/robinets\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"M\u00e9langeurs Bidet\",\"item\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/categorie-produit\\\/salle-de-bain\\\/robinets\\\/melangeurs-bidet\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Mitigeur De Bidet Avec Vidage Bellosta Zehn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/\",\"name\":\"CasaOmnia\",\"description\":\"La tua Casa in un Click\",\"publisher\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#organization\",\"name\":\"CasaOmnia Srl\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"contentUrl\":\"https:\\\/\\\/casaomnia.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-Logo-CasaOmnia-quadrato-2025.png\",\"width\":512,\"height\":512,\"caption\":\"CasaOmnia Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/casaomnia.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CasaOmnia.it\\\/\",\"https:\\\/\\\/x.com\\\/CasaOmnia_Shop\",\"https:\\\/\\\/www.instagram.com\\\/casaomnia\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/casaomnia\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/casaomnia\\\/\"],\"description\":\"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.\",\"email\":\"info@casaomnia.it\",\"telephone\":\"(+39) 081 1957 0168\",\"legalName\":\"CasaOmnia Srl\",\"foundingDate\":\"2016-05-05\",\"vatID\":\"IT10933861212\",\"taxID\":\"IT10933861212\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/casaomnia.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Bellosta\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"BELLOSTA086\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mitigeur De Bidet Avec Vidage Bellosta Zehn - CasaOmnia","description":"Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/","og_locale":"fr_FR","og_type":"article","og_title":"Mitigeur De Bidet Avec Vidage Bellosta Zehn - CasaOmnia","og_description":"Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.","og_url":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/","og_site_name":"CasaOmnia","article_publisher":"https:\/\/www.facebook.com\/CasaOmnia.it\/","article_modified_time":"2026-04-10T14:31:19+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CasaOmnia_Shop","twitter_misc":{"Disponibilit\u00e9":"En r\u00e9assort"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/","url":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/","name":"Mitigeur De Bidet Avec Vidage Bellosta Zehn - CasaOmnia","isPartOf":{"@id":"https:\/\/casaomnia.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/#primaryimage"},"image":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/#primaryimage"},"thumbnailUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg","datePublished":"2015-12-31T23:00:00+00:00","dateModified":"2026-04-10T14:31:19+00:00","description":"Le mitigeur de bidet Bellosta Zehn offre un design moderne ; avec une vidange int\u00e9gr\u00e9e, des tuyaux inclus et une finition chrom\u00e9e, il met en valeur toute salle de bains.","breadcrumb":{"@id":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/#primaryimage","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/1970\/01\/miscelatore-per-bidet-con-salterello-bellosta-zhen-rit2.jpg","width":1000,"height":1000,"caption":"bellosta zhen bidet mixer with pop-up waste"},{"@type":"BreadcrumbList","@id":"https:\/\/casaomnia.it\/fr\/shop\/mitigeur-de-bidet-avec-vidage-bellosta-zehn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaomnia.it\/fr\/home-20\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaomnia.it\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Salle de Bain","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/salle-de-bain\/"},{"@type":"ListItem","position":4,"name":"Robinets","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/salle-de-bain\/robinets\/"},{"@type":"ListItem","position":5,"name":"M\u00e9langeurs Bidet","item":"https:\/\/casaomnia.it\/fr\/categorie-produit\/salle-de-bain\/robinets\/melangeurs-bidet\/"},{"@type":"ListItem","position":6,"name":"Mitigeur De Bidet Avec Vidage Bellosta Zehn"}]},{"@type":"WebSite","@id":"https:\/\/casaomnia.it\/fr\/#website","url":"https:\/\/casaomnia.it\/fr\/","name":"CasaOmnia","description":"La tua Casa in un Click","publisher":{"@id":"https:\/\/casaomnia.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaomnia.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/casaomnia.it\/fr\/#organization","name":"CasaOmnia Srl","url":"https:\/\/casaomnia.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/casaomnia.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","contentUrl":"https:\/\/casaomnia.it\/wp-content\/uploads\/2025\/07\/cropped-Logo-CasaOmnia-quadrato-2025.png","width":512,"height":512,"caption":"CasaOmnia Srl"},"image":{"@id":"https:\/\/casaomnia.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CasaOmnia.it\/","https:\/\/x.com\/CasaOmnia_Shop","https:\/\/www.instagram.com\/casaomnia\/?hl=it","https:\/\/www.linkedin.com\/company\/casaomnia\/","https:\/\/www.pinterest.it\/casaomnia\/"],"description":"Qualit\u00e0 Made in Italy, tecnologie esclusive e design di tendenza al servizio dell\u2019uomo e delle sue emozioni. La mission di CasaOmnia? Offrirle ai consumatori pi\u00f9 esigenti in tutto il mondo. Il progetto \u00e8 nato dall\u2019intuizione dei fondatori, che per soddisfare la fame di bello, decidono di digitalizzare tutti i cataloghi della loro rivendita fisica e metterli a disposizione nel mercato e-commerce in Italia e nel mondo. Grazie ad un team giovane, unito e motivato che, attraverso una costante ricerca, riesce a proporre prodotti di tendenza in linea con le richieste del mercato. Oggi il marchio Casaomnia \u00e8 conosciuto e apprezzato in tutto il mondo, perch\u00e9 grazie alle relazioni con i consumatori ha realizzato un vasto catalogo incamerando non solo stile, innovazione e qualit\u00e0 superiore, ma anche esclusivit\u00e0 e possibilit\u00e0 di personalizzare l\u2019 acquisto e renderlo unico. Ogni acquisto \u00e8 seguito costantemente, dall\u2019ordine, alla realizzazione da parte dei nostri produttori Italiani, fino alla consegna presso la clientela finale, al fine di affermare un servizio sempre preciso e puntuale garantendo piena soddisfazione del cliente.","email":"info@casaomnia.it","telephone":"(+39) 081 1957 0168","legalName":"CasaOmnia Srl","foundingDate":"2016-05-05","vatID":"IT10933861212","taxID":"IT10933861212","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/casaomnia.it\/diritto-di-recesso\/"}}]},"product_brand":"Bellosta","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"BELLOSTA086","product_condition":"new"},"wcpa_form_fields":null,"_links":{"self":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product\/49850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/media\/346821"}],"wp:attachment":[{"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/media?parent=49850"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_brand?post=49850"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_cat?post=49850"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaomnia.it\/fr\/wp-json\/wp\/v2\/product_tag?post=49850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}